{"id":11530,"date":"2026-02-17T15:20:53","date_gmt":"2026-02-17T14:20:53","guid":{"rendered":"https:\/\/www.przedszkole4.bwi.pl\/?p=11530"},"modified":"2026-02-17T15:23:28","modified_gmt":"2026-02-17T14:23:28","slug":"mobilne-planetarium","status":"publish","type":"post","link":"https:\/\/www.przedszkole4.bwi.pl\/index.php\/2026\/02\/17\/mobilne-planetarium\/","title":{"rendered":"Mobilne planetarium"},"content":{"rendered":"<p>Mobilne planetarium to przeno\u015bna, nadmuchiwana kopu\u0142a projekcyjna, kt\u00f3ra umo\u017cliwia organizowanie pokaz\u00f3w astronomicznych i edukacyjnych w dowolnym miejscu, np. w przedszkolu. Jest to nowoczesne rozwi\u0105zanie, kt\u00f3re dzi\u0119ki technologii projekcji 360\u00b0 przenosi przedszkolak\u00f3w w wirtualn\u0105 podr\u00f3\u017c.<\/p>\n<div id='gallery-1' class='gallery galleryid-11530 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.przedszkole4.bwi.pl\/wp-content\/uploads\/2026\/02\/1000057136-768x1024.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.przedszkole4.bwi.pl\/wp-content\/uploads\/2026\/02\/1000057136-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-11528\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-11528'>\n\t\t\t\tMobilne planetarium\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.przedszkole4.bwi.pl\/wp-content\/uploads\/2026\/02\/1000057192-461x1024.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.przedszkole4.bwi.pl\/wp-content\/uploads\/2026\/02\/1000057192-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-11527\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-11527'>\n\t\t\t\tMobilne planetarium\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.przedszkole4.bwi.pl\/wp-content\/uploads\/2026\/02\/1000057207-768x1024.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.przedszkole4.bwi.pl\/wp-content\/uploads\/2026\/02\/1000057207-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-11526\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-11526'>\n\t\t\t\tMobilne planetarium\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.przedszkole4.bwi.pl\/wp-content\/uploads\/2026\/02\/1000057219-576x1024.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.przedszkole4.bwi.pl\/wp-content\/uploads\/2026\/02\/1000057219-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-11525\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-11525'>\n\t\t\t\tMobilne planetarium\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.przedszkole4.bwi.pl\/wp-content\/uploads\/2026\/02\/1000057139-768x1024.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.przedszkole4.bwi.pl\/wp-content\/uploads\/2026\/02\/1000057139-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-11524\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-11524'>\n\t\t\t\tMobilne planetarium\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Mobilne planetarium to przeno\u015bna, nadmuchiwana kopu\u0142a projekcyjna, kt\u00f3ra umo\u017cliwia organizowanie pokaz\u00f3w astronomicznych i edukacyjnych w dowolnym miejscu, np. w przedszkolu. Jest to nowoczesne rozwi\u0105zanie, kt\u00f3re dzi\u0119ki technologii projekcji 360\u00b0 przenosi przedszkolak\u00f3w w wirtualn\u0105 podr\u00f3\u017c.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.przedszkole4.bwi.pl\/index.php\/wp-json\/wp\/v2\/posts\/11530"}],"collection":[{"href":"https:\/\/www.przedszkole4.bwi.pl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.przedszkole4.bwi.pl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.przedszkole4.bwi.pl\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.przedszkole4.bwi.pl\/index.php\/wp-json\/wp\/v2\/comments?post=11530"}],"version-history":[{"count":2,"href":"https:\/\/www.przedszkole4.bwi.pl\/index.php\/wp-json\/wp\/v2\/posts\/11530\/revisions"}],"predecessor-version":[{"id":11532,"href":"https:\/\/www.przedszkole4.bwi.pl\/index.php\/wp-json\/wp\/v2\/posts\/11530\/revisions\/11532"}],"wp:attachment":[{"href":"https:\/\/www.przedszkole4.bwi.pl\/index.php\/wp-json\/wp\/v2\/media?parent=11530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.przedszkole4.bwi.pl\/index.php\/wp-json\/wp\/v2\/categories?post=11530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.przedszkole4.bwi.pl\/index.php\/wp-json\/wp\/v2\/tags?post=11530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}